{"id":62370,"date":"2025-05-20T07:38:34","date_gmt":"2025-05-20T05:38:34","guid":{"rendered":"https:\/\/www.inovex.de\/?post_type=trainers&#038;p=62370"},"modified":"2025-05-20T07:40:14","modified_gmt":"2025-05-20T05:40:14","slug":"david-zerulla","status":"publish","type":"trainers","link":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/","title":{"rendered":"David Zerulla"},"content":{"rendered":"<blockquote class=\"c-mrkdwn__quote\" data-stringify-type=\"quote\"><p><strong>David Zerulla<\/strong> ist seit 2017 als Backend- und Embedded-Entwickler f\u00fcr Android und Linux bei inovex t\u00e4tig. In dieser Zeit hat er vielseitige Projekte realisiert \u2013 von der Integration von Sensorhardware in Android \u00fcber die Entwicklung und Integration verschiedener Services ins AOSP (Android Open Source Project) bis hin zur Umsetzung von Cloud-Backends f\u00fcr IoT-Anwendungen in Go.<\/p><\/blockquote>\n","protected":false},"featured_media":62371,"template":"","class_list":["post-62370","trainers","type-trainers","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>David Zerulla - inovex GmbH<\/title>\n<meta name=\"description\" content=\"David Zerulla ist Trainer der inovex Academy.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"David Zerulla - inovex GmbH\" \/>\n<meta property=\"og:description\" content=\"David Zerulla ist Trainer der inovex Academy.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/\" \/>\n<meta property=\"og:site_name\" content=\"inovex GmbH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/inovexde\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-20T05:40:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"218\" \/>\n\t<meta property=\"og:image:height\" content=\"243\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@inovexgmbh\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathi Kersting\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/\",\"url\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/\",\"name\":\"David Zerulla - inovex GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.inovex.de\\\/wp-content\\\/uploads\\\/david_zerulla.jpg\",\"datePublished\":\"2025-05-20T05:38:34+00:00\",\"dateModified\":\"2025-05-20T05:40:14+00:00\",\"description\":\"David Zerulla ist Trainer der inovex Academy.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.inovex.de\\\/wp-content\\\/uploads\\\/david_zerulla.jpg\",\"contentUrl\":\"https:\\\/\\\/www.inovex.de\\\/wp-content\\\/uploads\\\/david_zerulla.jpg\",\"width\":218,\"height\":243,\"caption\":\"Schwarz-wei\u00df Bild von David Zerulla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/trainer\\\/david-zerulla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"David Zerulla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/\",\"name\":\"inovex GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#organization\",\"name\":\"inovex GmbH\",\"url\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.inovex.de\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/inovex-logo-16-9-1.png\",\"contentUrl\":\"https:\\\/\\\/www.inovex.de\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/inovex-logo-16-9-1.png\",\"width\":1921,\"height\":1081,\"caption\":\"inovex GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.inovex.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/inovexde\",\"https:\\\/\\\/x.com\\\/inovexgmbh\",\"https:\\\/\\\/www.instagram.com\\\/inovexlife\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/inovex\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7r66GT14hROB_RQsQBAQUQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"David Zerulla - inovex GmbH","description":"David Zerulla ist Trainer der inovex Academy.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/","og_locale":"de_DE","og_type":"article","og_title":"David Zerulla - inovex GmbH","og_description":"David Zerulla ist Trainer der inovex Academy.","og_url":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/","og_site_name":"inovex GmbH","article_publisher":"https:\/\/www.facebook.com\/inovexde","article_modified_time":"2025-05-20T05:40:14+00:00","og_image":[{"width":218,"height":243,"url":"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg","twitter_site":"@inovexgmbh","twitter_misc":{"Written by":"Kathi Kersting"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/","url":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/","name":"David Zerulla - inovex GmbH","isPartOf":{"@id":"https:\/\/www.inovex.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/#primaryimage"},"image":{"@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/#primaryimage"},"thumbnailUrl":"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg","datePublished":"2025-05-20T05:38:34+00:00","dateModified":"2025-05-20T05:40:14+00:00","description":"David Zerulla ist Trainer der inovex Academy.","breadcrumb":{"@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/#primaryimage","url":"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg","contentUrl":"https:\/\/www.inovex.de\/wp-content\/uploads\/david_zerulla.jpg","width":218,"height":243,"caption":"Schwarz-wei\u00df Bild von David Zerulla"},{"@type":"BreadcrumbList","@id":"https:\/\/www.inovex.de\/de\/trainer\/david-zerulla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.inovex.de\/de\/"},{"@type":"ListItem","position":2,"name":"David Zerulla"}]},{"@type":"WebSite","@id":"https:\/\/www.inovex.de\/de\/#website","url":"https:\/\/www.inovex.de\/de\/","name":"inovex GmbH","description":"","publisher":{"@id":"https:\/\/www.inovex.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.inovex.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.inovex.de\/de\/#organization","name":"inovex GmbH","url":"https:\/\/www.inovex.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.inovex.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.inovex.de\/wp-content\/uploads\/2021\/03\/inovex-logo-16-9-1.png","contentUrl":"https:\/\/www.inovex.de\/wp-content\/uploads\/2021\/03\/inovex-logo-16-9-1.png","width":1921,"height":1081,"caption":"inovex GmbH"},"image":{"@id":"https:\/\/www.inovex.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/inovexde","https:\/\/x.com\/inovexgmbh","https:\/\/www.instagram.com\/inovexlife\/","https:\/\/www.linkedin.com\/company\/inovex","https:\/\/www.youtube.com\/channel\/UC7r66GT14hROB_RQsQBAQUQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.inovex.de\/de\/wp-json\/wp\/v2\/trainers\/62370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inovex.de\/de\/wp-json\/wp\/v2\/trainers"}],"about":[{"href":"https:\/\/www.inovex.de\/de\/wp-json\/wp\/v2\/types\/trainers"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inovex.de\/de\/wp-json\/wp\/v2\/media\/62371"}],"wp:attachment":[{"href":"https:\/\/www.inovex.de\/de\/wp-json\/wp\/v2\/media?parent=62370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}